{"id":5713,"date":"2024-07-07T19:20:11","date_gmt":"2024-07-07T19:20:11","guid":{"rendered":"https:\/\/www.pondlehocky.com\/?post_type=team&#038;p=5713"},"modified":"2024-07-24T16:34:12","modified_gmt":"2024-07-24T16:34:12","slug":"dominique-ramer","status":"publish","type":"team","link":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/","title":{"rendered":"Dominique Ramer"},"content":{"rendered":"    <section class=\"pl-block pl-raw-content mb-7 pl-t [&#038;.border-t-2]:pt-8  \">\n        <h2 class=\"p1\">EDUCACI\u00d3N<\/h2>\n<ul class=\"ul1\">\n<li>Escuela de Derecho Whittier (2012)<\/li>\n<li>Universidad de Penn State (2007)<\/li>\n<\/ul>\n<p><strong>Dominique Ramer<\/strong>\u00a0se licenci\u00f3 en Justicia Penal en Penn State y se licenci\u00f3 en Derecho en la Whittier Law School. Est\u00e1 autorizada para ejercer la abogac\u00eda en Pensilvania y California.<\/p>\n<p>La Sra. Ramer comenz\u00f3 su carrera de abogada como pasante en la Oficina del Fiscal del Condado de Lehigh, en Pensilvania. A continuaci\u00f3n, realiz\u00f3 una pasant\u00eda legal en un bufete de abogados de California especializado en lesiones personales y fue asistente legal del Honorable Frederick Aguirre.<\/p>\n<p>La Sra. Ramer tiene una amplia experiencia en el manejo de asuntos de incapacidad de la Seguridad Social. La Sra. Ramer fue asistente legal y abogada asociada de un bufete con sede en Pensilvania, donde litig\u00f3 cientos de casos de incapacidad de la Seguridad Social, compensaci\u00f3n de trabajadores y lesiones personales. Antes de incorporarse a Pond Lehocky Disability, ejerci\u00f3 como abogada de indemnizaciones laborales en un gran bufete de defensa de California.<\/p>\n    <\/section>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7966,"parent":0,"template":"","class_list":["post-5713","team","type-team","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dominique Ramer | Abogado de la Seguridad Social por incapacidad | Pond Lehocky Giordano LLP<\/title>\n<meta name=\"description\" content=\"Practicando en PA y CA, Dominique Ramer se especializa como abogado para la incapacidad de la Seguridad Social con una amplia experiencia en el manejo de tales asuntos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our Attorneys | Pond Lehocky Giordano\" \/>\n<meta property=\"og:description\" content=\"Meet Pond Lehocky Giordano\u2019s workers\u2019 compensation, personal injury, Social Security disability, and long term disability attorneys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/\" \/>\n<meta property=\"og:site_name\" content=\"Pond Lehocky Giordano, Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/pondlehocky\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T16:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pondlehocky.com\/wp-content\/uploads\/2024\/07\/Dominque_Ramer.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"375\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/\",\"url\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/\",\"name\":\"Dominique Ramer | Abogado de la Seguridad Social por incapacidad | Pond Lehocky Giordano LLP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pondlehocky.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Dominque-Ramer.jpg\",\"datePublished\":\"2024-07-07T19:20:11+00:00\",\"dateModified\":\"2024-07-24T16:34:12+00:00\",\"description\":\"Practicando en PA y CA, Dominique Ramer se especializa como abogado para la incapacidad de la Seguridad Social con una amplia experiencia en el manejo de tales asuntos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pondlehocky.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Dominque-Ramer.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pondlehocky.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Dominque-Ramer.jpg\",\"width\":375,\"height\":469,\"caption\":\"Dominique Ramer, attorney for Pond Lehocky Giordano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/dominique-ramer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team\",\"item\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/nuestros-abogados\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dominique Ramer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/\",\"name\":\"Pond Lehocky\",\"description\":\"Largest workers\u2019 compensation and Social Security disability law firm in Pennsylvania\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/#organization\"},\"alternateName\":\"Pond Lehocky, Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/#organization\",\"name\":\"Pond Lehocky\",\"alternateName\":\"Pond Lehocky, Inc.\",\"url\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pondlehocky.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/pond-lehocky-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.pondlehocky.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/pond-lehocky-logo.png\",\"width\":355,\"height\":28,\"caption\":\"Pond Lehocky\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pondlehocky.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/pondlehocky\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/pondlehocky\",\"https:\\\/\\\/www.tiktok.com\\\/@pondlehockygiordano\",\"https:\\\/\\\/www.facebook.com\\\/PondLehocky\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pond-lehocky-giordano\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dominique Ramer | Abogado de la Seguridad Social por incapacidad | Pond Lehocky Giordano LLP","description":"Practicando en PA y CA, Dominique Ramer se especializa como abogado para la incapacidad de la Seguridad Social con una amplia experiencia en el manejo de tales asuntos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/","og_locale":"es_ES","og_type":"article","og_title":"Our Attorneys | Pond Lehocky Giordano","og_description":"Meet Pond Lehocky Giordano\u2019s workers\u2019 compensation, personal injury, Social Security disability, and long term disability attorneys","og_url":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/","og_site_name":"Pond Lehocky Giordano, Inc.","article_publisher":"https:\/\/www.instagram.com\/pondlehocky\/","article_modified_time":"2024-07-24T16:34:12+00:00","og_image":[{"width":375,"height":470,"url":"https:\/\/www.pondlehocky.com\/wp-content\/uploads\/2024\/07\/Dominque_Ramer.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/","url":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/","name":"Dominique Ramer | Abogado de la Seguridad Social por incapacidad | Pond Lehocky Giordano LLP","isPartOf":{"@id":"https:\/\/www.pondlehocky.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/#primaryimage"},"image":{"@id":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pondlehocky.com\/wp-content\/uploads\/2024\/07\/Dominque-Ramer.jpg","datePublished":"2024-07-07T19:20:11+00:00","dateModified":"2024-07-24T16:34:12+00:00","description":"Practicando en PA y CA, Dominique Ramer se especializa como abogado para la incapacidad de la Seguridad Social con una amplia experiencia en el manejo de tales asuntos.","breadcrumb":{"@id":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/#primaryimage","url":"https:\/\/www.pondlehocky.com\/wp-content\/uploads\/2024\/07\/Dominque-Ramer.jpg","contentUrl":"https:\/\/www.pondlehocky.com\/wp-content\/uploads\/2024\/07\/Dominque-Ramer.jpg","width":375,"height":469,"caption":"Dominique Ramer, attorney for Pond Lehocky Giordano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/dominique-ramer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pondlehocky.com\/es\/homepage\/"},{"@type":"ListItem","position":2,"name":"Team","item":"https:\/\/www.pondlehocky.com\/es\/nuestros-abogados\/"},{"@type":"ListItem","position":3,"name":"Dominique Ramer"}]},{"@type":"WebSite","@id":"https:\/\/www.pondlehocky.com\/es\/#website","url":"https:\/\/www.pondlehocky.com\/es\/","name":"Pond Lehocky","description":"Largest workers\u2019 compensation and Social Security disability law firm in Pennsylvania","publisher":{"@id":"https:\/\/www.pondlehocky.com\/es\/#organization"},"alternateName":"Pond Lehocky, Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pondlehocky.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pondlehocky.com\/es\/#organization","name":"Pond Lehocky","alternateName":"Pond Lehocky, Inc.","url":"https:\/\/www.pondlehocky.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pondlehocky.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.pondlehocky.com\/wp-content\/uploads\/2024\/04\/pond-lehocky-logo.png","contentUrl":"https:\/\/www.pondlehocky.com\/wp-content\/uploads\/2024\/04\/pond-lehocky-logo.png","width":355,"height":28,"caption":"Pond Lehocky"},"image":{"@id":"https:\/\/www.pondlehocky.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/pondlehocky\/","https:\/\/www.youtube.com\/user\/pondlehocky","https:\/\/www.tiktok.com\/@pondlehockygiordano","https:\/\/www.facebook.com\/PondLehocky","https:\/\/www.linkedin.com\/company\/pond-lehocky-giordano\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.pondlehocky.com\/es\/wp-json\/wp\/v2\/team\/5713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pondlehocky.com\/es\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/www.pondlehocky.com\/es\/wp-json\/wp\/v2\/types\/team"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pondlehocky.com\/es\/wp-json\/wp\/v2\/media\/7966"}],"wp:attachment":[{"href":"https:\/\/www.pondlehocky.com\/es\/wp-json\/wp\/v2\/media?parent=5713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}